{"id":1,"count":0,"description":"","link":"https:\/\/slides.bytethebuzz.com\/index.php\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/slides.bytethebuzz.com\/index.php\/wp-json\/wp\/v2\/categories\/1"}],"collection":[{"href":"https:\/\/slides.bytethebuzz.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/slides.bytethebuzz.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/slides.bytethebuzz.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}